{"id":132506,"date":"1996-01-01T00:00:00","date_gmt":"1996-01-01T00:00:00","guid":{"rendered":"https:\/\/www.deberes.net\/tesis\/sin-categoria\/hacia-un-cambio-climatico-las-tendencias-del-clima-en-la-cuenca-occidental-del-mediterraneo-desde-mediados-del-siglo-xix\/"},"modified":"1996-01-01T00:00:00","modified_gmt":"1996-01-01T00:00:00","slug":"hacia-un-cambio-climatico-las-tendencias-del-clima-en-la-cuenca-occidental-del-mediterraneo-desde-mediados-del-siglo-xix","status":"publish","type":"post","link":"https:\/\/www.deberes.net\/tesis\/ciencias-de-la-tierra-y-del-espacio\/hacia-un-cambio-climatico-las-tendencias-del-clima-en-la-cuenca-occidental-del-mediterraneo-desde-mediados-del-siglo-xix\/","title":{"rendered":"Hacia un cambio climatico?: las tendencias del clima en la cuenca occidental del mediterraneo desde mediados del siglo xix."},"content":{"rendered":"<h2>Tesis doctoral de <strong> Enrique Monton Chiva <\/strong><\/h2>\n<p>Nuestro planeta esta experimentando actualmente una serie de anomalias climaticas que nos llevan a buscar sus causas y potenciales consecuencias, como son la elevacion del nivel marino, el incremento termico, generalizado en la cuenca occidental del mediterraneo, y las variaciones pluviometricas seculares, de menor rango que las termicas y de signo cambiante segun las areas, en base a los resultados de nuestro estudio.A la hora de conocer las causas de estos cambios, la radiacion solar, en incremento secular, no basta como respuesta unica. Por otra parte, surgen dudas acerca de los gases invernadero.  la evolucion ascendente del principal de ellos, el co2, no ha sido paralela a la de las temperaturas, ya que la del primero es de una regularidad extraordinaria no presente en la evolucion termica.  otros dos factores intervienen. De un lado, las erupciones volcanicas, de sensible efecto de urbanizacion, sobre los observatorios en su mayoria inmersos en grandes ciudades. Considerado el primero y corregido el segundo, el incremento secular de las temperaturas mediterraneas podia explicarse a partir de un indice solar-volcanico. No obstante, y aunque todavia nada parece fuera del control natural, la alerta y las incertidumbres deben incentivar las investigaciones hacia factores como son la disminucion en el espesor de la capa de ozono.<\/p>\n<p>&nbsp;<\/p>\n<h3>Datos acad\u00e9micos de la tesis doctoral \u00ab<strong>Hacia un cambio climatico?: las tendencias del clima en la cuenca occidental del mediterraneo desde mediados del siglo xix.<\/strong>\u00ab<\/h3>\n<ul>\n<li><strong>T\u00edtulo de la tesis:<\/strong>\u00a0 Hacia un cambio climatico?: las tendencias del clima en la cuenca occidental del mediterraneo desde mediados del siglo xix. <\/li>\n<li><strong>Autor:<\/strong>\u00a0 Enrique Monton Chiva <\/li>\n<li><strong>Universidad:<\/strong>\u00a0 Jaume i de castell\u00f3n<\/li>\n<li><strong>Fecha de lectura de la tesis:<\/strong>\u00a0 01\/01\/1996<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Direcci\u00f3n y tribunal<\/h3>\n<ul>\n<li><strong>Director de la tesis<\/strong>\n<ul>\n<li>Jos\u00e9 Quereda Sala<\/li>\n<\/ul>\n<\/li>\n<li><strong>Tribunal<\/strong>\n<ul>\n<li>Presidente del tribunal: Antonio Gil Olcina <\/li>\n<li>Javier Martin Vide (vocal)<\/li>\n<li>Alejandro Perez Cueva (vocal)<\/li>\n<li>Jorge Olcina Cantos (vocal)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tesis doctoral de Enrique Monton Chiva Nuestro planeta esta experimentando actualmente una serie de anomalias climaticas que nos llevan a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[20341,27,4329,18725,4328],"tags":[177103,11875,246346,4331,67710,19355],"class_list":["post-132506","post","type-post","status-publish","format-standard","hentry","category-cambio-climatico","category-ciencias-de-la-tierra-y-del-espacio","category-climatologia","category-jaume-i-de-castellon","category-paleoclimatologia","tag-alejandro-perez-cueva","tag-antonio-gil-olcina","tag-enrique-monton-chiva","tag-javier-martin-vide","tag-jorge-olcina-cantos","tag-jose-quereda-sala"],"_links":{"self":[{"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/posts\/132506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/comments?post=132506"}],"version-history":[{"count":0,"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/posts\/132506\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/media?parent=132506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/categories?post=132506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deberes.net\/tesis\/wp-json\/wp\/v2\/tags?post=132506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}